{"id":76958,"date":"2023-02-21T17:56:33","date_gmt":"2023-02-21T16:56:33","guid":{"rendered":"https:\/\/www.intarcon.com\/la-refrigeracion-como-aporte-de-calidad-y-seguridad-al-industria-carnica\/"},"modified":"2024-12-12T09:54:15","modified_gmt":"2024-12-12T08:54:15","slug":"a-refrigeracao-como-contributo-para-a-qualidade-e-seguranca-na-industria-da-carne","status":"publish","type":"post","link":"https:\/\/www.intarcon.com\/pt-pt\/a-refrigeracao-como-contributo-para-a-qualidade-e-seguranca-na-industria-da-carne\/","title":{"rendered":"A refrigera\u00e7\u00e3o como contributo para a qualidade e seguran\u00e7a na ind\u00fastria da carne"},"content":{"rendered":"<p><strong>&#8220;Com o objectivo de contribuir para a disponibilidade de alimentos para uma popula\u00e7\u00e3o em constante crescimento, exigente com a qualidade dos produtos da ind\u00fastria da carne. INTARCON oferece solu\u00e7\u00f5es em refrigera\u00e7\u00e3o de m\u00e3os dadas com a efici\u00eancia energ\u00e9tica e o controlo da seguran\u00e7a alimentar&#8221;.<\/strong><\/p>\n<p>A carne torna-se um meio de cultura ideal para o crescimento de quase todos os microrganismos. Isto deve-se ao facto de:<\/p>\n<ul>\n<li>Qualidades nutricionais, pH neutro post-mortem (pH = 6,5).<\/li>\n<li>Actividade h\u00eddrica elevada (aw = 0,98).<\/li>\n<li>Factores extr\u00ednsecos como a temperatura e a concentra\u00e7\u00e3o de oxig\u00e9nio.<\/li>\n<\/ul>\n<p>A carne e os produtos \u00e0 base de carne s\u00e3o perec\u00edveis por natureza e facilmente suscept\u00edveis de contamina\u00e7\u00e3o microbiana e de deteriora\u00e7\u00e3o qu\u00edmica. Certos processos provocam altera\u00e7\u00f5es indesej\u00e1veis na qualidade e alteram a cor, a textura e o sabor&#8230; Representam n\u00e3o s\u00f3 um risco para a sa\u00fade dos consumidores, mas tamb\u00e9m, eventualmente, uma perda econ\u00f3mica.<\/p>\n<p>Durante os \u00faltimos anos, a procura de alimentos de qualidade com elevado valor nutricional, mas sem conservantes qu\u00edmicos, aumentou. Este facto deve-se \u00e0 mudan\u00e7a do estilo de vida e dos h\u00e1bitos alimentares dos consumidores, que se est\u00e3o a tornar cada vez mais exigentes.<\/p>\n<h2>A refrigera\u00e7\u00e3o como parte fundamental do processo de conserva\u00e7\u00e3o na ind\u00fastria da carne<\/h2>\n<p><strong>A refrigera\u00e7\u00e3o desempenha um papel fundamental<\/strong> durante o <strong>processo de conserva\u00e7\u00e3o da carne<\/strong>, pois impede o crescimento de microrganismos patog\u00e9nicos como Salmonella, Listeria ou Enterobacteriaceae (como E. Coli). Estas bact\u00e9rias s\u00e3o capazes de causar intoxica\u00e7\u00e3o ou mesmo a morte do indiv\u00edduo; e n\u00e3o agentes patog\u00e9nicos que podem alterar as caracter\u00edsticas organol\u00e9pticas ou o aspecto do produto, tornando-o impr\u00f3prio para consumo. Por esta raz\u00e3o, devem ser tomadas medidas de<a href=\"https:\/\/www.intarcon.com\/pt-pt\/as-melhores-camaras-de-refrigeracao-de-carne\/\"> higiene e controlo nas c\u00e2maras frigor\u00edficas<\/a>, levando o produto a baixas temperaturas, de forma a retardar ou parar a actividade microbiol\u00f3gica e as reac\u00e7\u00f5es bioqu\u00edmicas.<\/p>\n<p>Temperaturas inferiores a cerca de -2 \u00b0C, consoante o tipo de carne. Isto leva \u00e0 forma\u00e7\u00e3o de cristais de gelo nos espa\u00e7os intercelulares, provocando a sa\u00edda de \u00e1gua das c\u00e9lulas para compensar o aumento da press\u00e3o osm\u00f3tica. Isto leva \u00e0 secagem do produto, resultando em perda de peso e altera\u00e7\u00e3o da estrutura celular. Tudo isto resulta numa menor qualidade percebida pelo utilizador.<\/p>\n<h2>Solu\u00e7\u00f5es de refrigera\u00e7\u00e3o para a ind\u00fastria da carne<\/h2>\n<p>A INTARCON concebeu <em>evaporadores de parede para t\u00faneis de congela\u00e7\u00e3o com ventiladores de alto caudal e alta press\u00e3o est\u00e1tica<\/em>, dispon\u00edveis em conjunto com serpentinas de alta efici\u00eancia. Estas unidades reduzem o tempo de congela\u00e7\u00e3o e favorecem a forma\u00e7\u00e3o de cristais mais pequenos.<\/p>\n<p>Para responder a estas exig\u00eancias de grande capacidade de refrigera\u00e7\u00e3o, a INTARCON oferece <strong>solu\u00e7\u00f5es e sistemas de refrigera\u00e7\u00e3o que utilizam refrigerantes naturais<\/strong> (como o <a href=\"https:\/\/www.intarcon.com\/tecnologia\/nh3\/\">amon\u00edaco (R-717)<\/a>, o <a href=\"https:\/\/www.intarcon.com\/tecnologia\/r290\/\">propano (R-290)<\/a> ou o <a href=\"https:\/\/www.intarcon.com\/tecnologia\/co2\/\">CO2 (R-744)<\/a> prontos a entrar em funcionamento gra\u00e7as \u00e0 sua configura\u00e7\u00e3o Plug &amp; Play.<\/p>\n<p><a href=\"https:\/\/www.intarcon.com\/el-papel-de-los-refrigerantes-naturales-en-la-climatizacion-y-refrigeracion\/\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-73214\" src=\"https:\/\/www.intarcon.com\/wp-content\/uploads\/2023\/02\/gama-naturales.webp\" alt=\"gama-naturales-intarcon\" width=\"850\" height=\"211\" \/><\/a><\/p>\n<p>As salas de corte ou processamento est\u00e3o entre as \u00e1reas com maior risco de contamina\u00e7\u00e3o, sendo classificadas como um ponto cr\u00edtico de controlo na cadeia de frio. Recomendamos a utiliza\u00e7\u00e3o de equipamentos que reduzam a carga microbiana em suspens\u00e3o <strong>com purificadores de ar e controlo da temperatura ambiente.<\/strong> Para isso, INTARCON desenvolveu o equipamento<a href=\"https:\/\/www.intarcon.com\/intarsanit\/\"> intarSANIT<\/a>, baseado na utiliza\u00e7\u00e3o de etapas de filtra\u00e7\u00e3o HEPA e luz UV-C, ou recupera\u00e7\u00e3o de calor do ar de extrac\u00e7\u00e3o.<\/p>\n<h3><\/h3>\n<p><img decoding=\"async\" class=\" wp-image-89147 aligncenter\" src=\"https:\/\/www.intarcon.com\/wp-content\/uploads\/2021\/04\/ventilacion-renovacion-aire-intarsanit-tch.webp\" alt=\"Equipo de ventilaci\u00f3n para la ventilaci\u00f3n y renovaci\u00f3n de aire intarSANIT - INTARCON\" width=\"301\" height=\"301\" \/><\/p>\n<h3>Conserva\u00e7\u00e3o e matura\u00e7\u00e3o da carne<\/h3>\n<p>A <a href=\"https:\/\/www.intarcon.com\/producto\/carne\/\">matura\u00e7\u00e3o da carne<\/a> representa uma oportunidade econ\u00f3mica, pois permite a revaloriza\u00e7\u00e3o do produto em resposta aos novos h\u00e1bitos dos consumidores, ao seu interesse pela qualidade e \u00e0 sua preocupa\u00e7\u00e3o com a seguran\u00e7a. Por esta raz\u00e3o, h\u00e1 cada vez mais casos de empresas que criam uma nova linha de comercializa\u00e7\u00e3o para a carne maturada. As duas principais linhas de carne maturada s\u00e3o:<\/p>\n<ul>\n<li><span style=\"text-decoration: underline;\">Matura\u00e7\u00e3o h\u00famida da carne,<\/span> cujo objectivo \u00e9 controlar a actividade microbiol\u00f3gica das bact\u00e9rias aer\u00f3bias mes\u00f3filas e \u00e1cido-l\u00e1cticas. A carne deve ter um pH &lt; 5,8, uma temperatura entre 1 \u00b0C e 4 \u00b0C e uma atmosfera pobre em oxig\u00e9nio. Para este tipo de matura\u00e7\u00e3o, o produto \u00e9 embalado em v\u00e1cuo ou em sacos que permitam a passagem da humidade.<\/li>\n<li><span style=\"text-decoration: underline;\">A matura\u00e7\u00e3o das carnes envelhecidas a seco<\/span> baseia-se na decomposi\u00e7\u00e3o das prote\u00ednas miofibrilares pela ac\u00e7\u00e3o das enzimas presentes na carne, amolecendo assim as fibras musculares. A investiga\u00e7\u00e3o levada a cabo pelo IRTA (<a href=\"https:\/\/www.irta.cat\/es\/\">Instituto de Investiga\u00e7\u00e3o e Tecnologia Agro-alimentar<\/a>) obteve resultados que permitem antecipar o efeito dos factores intr\u00ednsecos (pH, gordura, etc.) e extr\u00ednsecos (temperatura e humidade relativa) sobre o crescimento microbiano, o que permite dar orienta\u00e7\u00f5es de seguran\u00e7a neste processo complexo. Para o efeito, o IRTA recomenda que a temperatura seja inferior a 2 \u00b0C, que as carnes com pH &gt; 5,6 sejam rejeitadas e que a actividade da \u00e1gua superficial n\u00e3o atinja valores inferiores a 0,95.<\/li>\n<\/ul>\n<h4>Processo de matura\u00e7\u00e3o da carne<\/h4>\n<p>O <strong>processo de cura da carne<\/strong> confere qualidade, seguran\u00e7a e prazo de validade ao produto, consistindo na secagem da parte externa do produto, que impede o estabelecimento de microrganismos, atrav\u00e9s de uma fase pr\u00e9via de salga e posterior controlo numa c\u00e2mara onde a humidade \u00e9 progressivamente reduzida. Nesta \u00faltima fase, ocorrem as reac\u00e7\u00f5es qu\u00edmicas e enzim\u00e1ticas que dar\u00e3o origem aos compostos organol\u00e9pticos pretendidos.<\/p>\n<p><img decoding=\"async\" class=\" wp-image-89297 aligncenter\" src=\"https:\/\/www.intarcon.com\/wp-content\/uploads\/2019\/06\/equipo-semicompacto-maduracion-conservacion-carne.webp\" alt=\"Equipo semicompacto de refrigeraci\u00f3n para conservaci\u00f3n y maduraci\u00f3n de carne - INTARCON\" width=\"391\" height=\"391\" \/><\/p>\n<h4>Conserva\u00e7\u00e3o da carne<\/h4>\n<p>Para contribuir para os processos acima mencionados, a INTARCON desenvolveu <a href=\"https:\/\/www.intarcon.com\/producto\/carne\/\">equipamentos para a matura\u00e7\u00e3o e conserva\u00e7\u00e3o de carnes<\/a> com controlo de humidade opcional, equipados com evaporadores quase-est\u00e1ticos de duplo fluxo a muito baixa velocidade, com o objectivo de evitar a altera\u00e7\u00e3o do produto e controlar a humidade na c\u00e2mara.<\/p>\n<p>&nbsp;<\/p>\n<p>Para al\u00e9m da qualidade e facilidade de instala\u00e7\u00e3o dos equipamentos, a INTARCON destaca-se pela sua capacidade de assessoria e concep\u00e7\u00e3o de projectos de refrigera\u00e7\u00e3o. Dispomos de uma ampla equipa comercial e de prescri\u00e7\u00e3o com ampla experi\u00eancia e forma\u00e7\u00e3o para a execu\u00e7\u00e3o de projectos dirigidos ao <a href=\"https:\/\/www.intarcon.com\/pt-pt\/solucoes-de-refrigeracao-para-a-industria-agro-alimentar\/\">sector agro-alimentar<\/a>, cujo objectivo \u00e9 oferecer a melhor solu\u00e7\u00e3o, analisando todas as alternativas e propondo a mais eficiente, fi\u00e1vel e sustent\u00e1vel para o cliente.<\/p>\n<p><a href=\"https:\/\/www.intarcon.com\/asesoria-tecnica-2\/\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-64290 size-full aligncenter\" src=\"https:\/\/www.intarcon.com\/wp-content\/uploads\/2022\/06\/CTA-Solicitar-Asesoria-PT.jpg\" alt=\"Pedir aconselhamento t\u00e9cnico - INTARCON\" width=\"1191\" height=\"347\" srcset=\"https:\/\/www.intarcon.com\/wp-content\/uploads\/2022\/06\/CTA-Solicitar-Asesoria-PT.jpg 1191w, https:\/\/www.intarcon.com\/wp-content\/uploads\/2022\/06\/CTA-Solicitar-Asesoria-PT-768x224.jpg 768w, https:\/\/www.intarcon.com\/wp-content\/uploads\/2022\/06\/CTA-Solicitar-Asesoria-PT-640x186.jpg 640w, https:\/\/www.intarcon.com\/wp-content\/uploads\/2022\/06\/CTA-Solicitar-Asesoria-PT-400x117.jpg 400w, https:\/\/www.intarcon.com\/wp-content\/uploads\/2022\/06\/CTA-Solicitar-Asesoria-PT-367x107.jpg 367w, https:\/\/www.intarcon.com\/wp-content\/uploads\/2022\/06\/CTA-Solicitar-Asesoria-PT-600x175.jpg 600w\" sizes=\"(max-width: 1191px) 100vw, 1191px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><em>Por <a href=\"https:\/\/www.linkedin.com\/in\/nil-servi%C3%A1n-vives-527648155\/\">Nil Servi\u00e1n<\/a>, Editor de Documenta\u00e7\u00e3o da INTARCON, Licenciado em Biologia com Mestrado em Avan\u00e7os em Seguran\u00e7a Alimentar.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Com o objectivo de contribuir para a disponibilidade de alimentos para uma popula\u00e7\u00e3o em constante crescimento, exigente com a qualidade dos produtos da ind\u00fastria da carne. INTARCON oferece solu\u00e7\u00f5es em refrigera\u00e7\u00e3o de m\u00e3os dadas com a efici\u00eancia energ\u00e9tica e o controlo da seguran\u00e7a alimentar&#8221;. A carne torna-se um meio de cultura ideal para o crescimento [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":73213,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[597,646,684],"tags":[],"class_list":["post-76958","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blogue","category-camaras-frigorificas-pt","category-refrigeracao-de-alimentos"],"featured_image_src":{"landsacpe":["https:\/\/www.intarcon.com\/wp-content\/uploads\/2023\/02\/refrigeracion-calidad-seguridad-sector-carnico-1140x445.webp",1140,445,true],"list":["https:\/\/www.intarcon.com\/wp-content\/uploads\/2023\/02\/refrigeracion-calidad-seguridad-sector-carnico-463x348.webp",463,348,true],"medium":["https:\/\/www.intarcon.com\/wp-content\/uploads\/2023\/02\/refrigeracion-calidad-seguridad-sector-carnico.webp",1465,976,false],"full":["https:\/\/www.intarcon.com\/wp-content\/uploads\/2023\/02\/refrigeracion-calidad-seguridad-sector-carnico.webp",1465,976,false]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Refrigera\u00e7\u00e3o para a ind\u00fastria da carne - INTARCON<\/title>\n<meta name=\"description\" content=\"Solu\u00e7\u00f5es de refrigera\u00e7\u00e3o para a conserva\u00e7\u00e3o dos produtos na ind\u00fastria da carne. C\u00e2maras frigor\u00edficas, transforma\u00e7\u00e3o e matura\u00e7\u00e3o de produtos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.intarcon.com\/pt-pt\/a-refrigeracao-como-contributo-para-a-qualidade-e-seguranca-na-industria-da-carne\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Refrigera\u00e7\u00e3o para a ind\u00fastria da carne - INTARCON\" \/>\n<meta property=\"og:description\" content=\"Solu\u00e7\u00f5es de refrigera\u00e7\u00e3o para a conserva\u00e7\u00e3o dos produtos na ind\u00fastria da carne. C\u00e2maras frigor\u00edficas, transforma\u00e7\u00e3o e matura\u00e7\u00e3o de produtos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.intarcon.com\/pt-pt\/a-refrigeracao-como-contributo-para-a-qualidade-e-seguranca-na-industria-da-carne\/\" \/>\n<meta property=\"og:site_name\" content=\"INTARCON\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/intarcon\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-21T16:56:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-12T08:54:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.intarcon.com\/wp-content\/uploads\/2023\/02\/refrigeracion-calidad-seguridad-sector-carnico.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1465\" \/>\n\t<meta property=\"og:image:height\" content=\"976\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"INTARCON\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Intarcon\" \/>\n<meta name=\"twitter:site\" content=\"@Intarcon\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"INTARCON\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.intarcon.com\\\/pt-pt\\\/a-refrigeracao-como-contributo-para-a-qualidade-e-seguranca-na-industria-da-carne\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.intarcon.com\\\/pt-pt\\\/a-refrigeracao-como-contributo-para-a-qualidade-e-seguranca-na-industria-da-carne\\\/\"},\"author\":{\"name\":\"INTARCON\",\"@id\":\"https:\\\/\\\/www.intarcon.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/3953ab26cc806bd58bd91f8a62054c03\"},\"headline\":\"A refrigera\u00e7\u00e3o como contributo para a qualidade e seguran\u00e7a na ind\u00fastria da carne\",\"datePublished\":\"2023-02-21T16:56:33+00:00\",\"dateModified\":\"2024-12-12T08:54:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.intarcon.com\\\/pt-pt\\\/a-refrigeracao-como-contributo-para-a-qualidade-e-seguranca-na-industria-da-carne\\\/\"},\"wordCount\":1108,\"image\":{\"@id\":\"https:\\\/\\\/www.intarcon.com\\\/pt-pt\\\/a-refrigeracao-como-contributo-para-a-qualidade-e-seguranca-na-industria-da-carne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.intarcon.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/refrigeracion-calidad-seguridad-sector-carnico.webp\",\"articleSection\":[\"Blogue\",\"C\u00e2maras frigor\u00edficas\",\"Refrigera\u00e7\u00e3o de alimentos\"],\"inLanguage\":\"pt\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.intarcon.com\\\/pt-pt\\\/a-refrigeracao-como-contributo-para-a-qualidade-e-seguranca-na-industria-da-carne\\\/\",\"url\":\"https:\\\/\\\/www.intarcon.com\\\/pt-pt\\\/a-refrigeracao-como-contributo-para-a-qualidade-e-seguranca-na-industria-da-carne\\\/\",\"name\":\"Refrigera\u00e7\u00e3o para a ind\u00fastria da carne - INTARCON\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.intarcon.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.intarcon.com\\\/pt-pt\\\/a-refrigeracao-como-contributo-para-a-qualidade-e-seguranca-na-industria-da-carne\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.intarcon.com\\\/pt-pt\\\/a-refrigeracao-como-contributo-para-a-qualidade-e-seguranca-na-industria-da-carne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.intarcon.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/refrigeracion-calidad-seguridad-sector-carnico.webp\",\"datePublished\":\"2023-02-21T16:56:33+00:00\",\"dateModified\":\"2024-12-12T08:54:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.intarcon.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/3953ab26cc806bd58bd91f8a62054c03\"},\"description\":\"Solu\u00e7\u00f5es de refrigera\u00e7\u00e3o para a conserva\u00e7\u00e3o dos produtos na ind\u00fastria da carne. C\u00e2maras frigor\u00edficas, transforma\u00e7\u00e3o e matura\u00e7\u00e3o de produtos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.intarcon.com\\\/pt-pt\\\/a-refrigeracao-como-contributo-para-a-qualidade-e-seguranca-na-industria-da-carne\\\/#breadcrumb\"},\"inLanguage\":\"pt\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.intarcon.com\\\/pt-pt\\\/a-refrigeracao-como-contributo-para-a-qualidade-e-seguranca-na-industria-da-carne\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt\",\"@id\":\"https:\\\/\\\/www.intarcon.com\\\/pt-pt\\\/a-refrigeracao-como-contributo-para-a-qualidade-e-seguranca-na-industria-da-carne\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.intarcon.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/refrigeracion-calidad-seguridad-sector-carnico.webp\",\"contentUrl\":\"https:\\\/\\\/www.intarcon.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/refrigeracion-calidad-seguridad-sector-carnico.webp\",\"width\":1465,\"height\":976,\"caption\":\"refrigeraci\u00f3n-calidad-seguridad-sector-carnico\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.intarcon.com\\\/pt-pt\\\/a-refrigeracao-como-contributo-para-a-qualidade-e-seguranca-na-industria-da-carne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.intarcon.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blogue\",\"item\":\"https:\\\/\\\/www.intarcon.com\\\/pt-pt\\\/category\\\/blogue\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"A refrigera\u00e7\u00e3o como contributo para a qualidade e seguran\u00e7a na ind\u00fastria da carne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.intarcon.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/www.intarcon.com\\\/pt-pt\\\/\",\"name\":\"INTARCON\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.intarcon.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.intarcon.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/3953ab26cc806bd58bd91f8a62054c03\",\"name\":\"INTARCON\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/15e7dea3e8aff0fc73c1fbe5156ed313f6044f5727ad9a8c9752574cacdce03d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/15e7dea3e8aff0fc73c1fbe5156ed313f6044f5727ad9a8c9752574cacdce03d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/15e7dea3e8aff0fc73c1fbe5156ed313f6044f5727ad9a8c9752574cacdce03d?s=96&d=mm&r=g\",\"caption\":\"INTARCON\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Refrigera\u00e7\u00e3o para a ind\u00fastria da carne - INTARCON","description":"Solu\u00e7\u00f5es de refrigera\u00e7\u00e3o para a conserva\u00e7\u00e3o dos produtos na ind\u00fastria da carne. C\u00e2maras frigor\u00edficas, transforma\u00e7\u00e3o e matura\u00e7\u00e3o de produtos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.intarcon.com\/pt-pt\/a-refrigeracao-como-contributo-para-a-qualidade-e-seguranca-na-industria-da-carne\/","og_locale":"pt_PT","og_type":"article","og_title":"Refrigera\u00e7\u00e3o para a ind\u00fastria da carne - INTARCON","og_description":"Solu\u00e7\u00f5es de refrigera\u00e7\u00e3o para a conserva\u00e7\u00e3o dos produtos na ind\u00fastria da carne. C\u00e2maras frigor\u00edficas, transforma\u00e7\u00e3o e matura\u00e7\u00e3o de produtos.","og_url":"https:\/\/www.intarcon.com\/pt-pt\/a-refrigeracao-como-contributo-para-a-qualidade-e-seguranca-na-industria-da-carne\/","og_site_name":"INTARCON","article_publisher":"https:\/\/www.facebook.com\/intarcon\/","article_published_time":"2023-02-21T16:56:33+00:00","article_modified_time":"2024-12-12T08:54:15+00:00","og_image":[{"width":1465,"height":976,"url":"https:\/\/www.intarcon.com\/wp-content\/uploads\/2023\/02\/refrigeracion-calidad-seguridad-sector-carnico.webp","type":"image\/webp"}],"author":"INTARCON","twitter_card":"summary_large_image","twitter_creator":"@Intarcon","twitter_site":"@Intarcon","twitter_misc":{"Written by":"INTARCON","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.intarcon.com\/pt-pt\/a-refrigeracao-como-contributo-para-a-qualidade-e-seguranca-na-industria-da-carne\/#article","isPartOf":{"@id":"https:\/\/www.intarcon.com\/pt-pt\/a-refrigeracao-como-contributo-para-a-qualidade-e-seguranca-na-industria-da-carne\/"},"author":{"name":"INTARCON","@id":"https:\/\/www.intarcon.com\/pt-pt\/#\/schema\/person\/3953ab26cc806bd58bd91f8a62054c03"},"headline":"A refrigera\u00e7\u00e3o como contributo para a qualidade e seguran\u00e7a na ind\u00fastria da carne","datePublished":"2023-02-21T16:56:33+00:00","dateModified":"2024-12-12T08:54:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.intarcon.com\/pt-pt\/a-refrigeracao-como-contributo-para-a-qualidade-e-seguranca-na-industria-da-carne\/"},"wordCount":1108,"image":{"@id":"https:\/\/www.intarcon.com\/pt-pt\/a-refrigeracao-como-contributo-para-a-qualidade-e-seguranca-na-industria-da-carne\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intarcon.com\/wp-content\/uploads\/2023\/02\/refrigeracion-calidad-seguridad-sector-carnico.webp","articleSection":["Blogue","C\u00e2maras frigor\u00edficas","Refrigera\u00e7\u00e3o de alimentos"],"inLanguage":"pt"},{"@type":"WebPage","@id":"https:\/\/www.intarcon.com\/pt-pt\/a-refrigeracao-como-contributo-para-a-qualidade-e-seguranca-na-industria-da-carne\/","url":"https:\/\/www.intarcon.com\/pt-pt\/a-refrigeracao-como-contributo-para-a-qualidade-e-seguranca-na-industria-da-carne\/","name":"Refrigera\u00e7\u00e3o para a ind\u00fastria da carne - INTARCON","isPartOf":{"@id":"https:\/\/www.intarcon.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.intarcon.com\/pt-pt\/a-refrigeracao-como-contributo-para-a-qualidade-e-seguranca-na-industria-da-carne\/#primaryimage"},"image":{"@id":"https:\/\/www.intarcon.com\/pt-pt\/a-refrigeracao-como-contributo-para-a-qualidade-e-seguranca-na-industria-da-carne\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intarcon.com\/wp-content\/uploads\/2023\/02\/refrigeracion-calidad-seguridad-sector-carnico.webp","datePublished":"2023-02-21T16:56:33+00:00","dateModified":"2024-12-12T08:54:15+00:00","author":{"@id":"https:\/\/www.intarcon.com\/pt-pt\/#\/schema\/person\/3953ab26cc806bd58bd91f8a62054c03"},"description":"Solu\u00e7\u00f5es de refrigera\u00e7\u00e3o para a conserva\u00e7\u00e3o dos produtos na ind\u00fastria da carne. C\u00e2maras frigor\u00edficas, transforma\u00e7\u00e3o e matura\u00e7\u00e3o de produtos.","breadcrumb":{"@id":"https:\/\/www.intarcon.com\/pt-pt\/a-refrigeracao-como-contributo-para-a-qualidade-e-seguranca-na-industria-da-carne\/#breadcrumb"},"inLanguage":"pt","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.intarcon.com\/pt-pt\/a-refrigeracao-como-contributo-para-a-qualidade-e-seguranca-na-industria-da-carne\/"]}]},{"@type":"ImageObject","inLanguage":"pt","@id":"https:\/\/www.intarcon.com\/pt-pt\/a-refrigeracao-como-contributo-para-a-qualidade-e-seguranca-na-industria-da-carne\/#primaryimage","url":"https:\/\/www.intarcon.com\/wp-content\/uploads\/2023\/02\/refrigeracion-calidad-seguridad-sector-carnico.webp","contentUrl":"https:\/\/www.intarcon.com\/wp-content\/uploads\/2023\/02\/refrigeracion-calidad-seguridad-sector-carnico.webp","width":1465,"height":976,"caption":"refrigeraci\u00f3n-calidad-seguridad-sector-carnico"},{"@type":"BreadcrumbList","@id":"https:\/\/www.intarcon.com\/pt-pt\/a-refrigeracao-como-contributo-para-a-qualidade-e-seguranca-na-industria-da-carne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.intarcon.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Blogue","item":"https:\/\/www.intarcon.com\/pt-pt\/category\/blogue\/"},{"@type":"ListItem","position":3,"name":"A refrigera\u00e7\u00e3o como contributo para a qualidade e seguran\u00e7a na ind\u00fastria da carne"}]},{"@type":"WebSite","@id":"https:\/\/www.intarcon.com\/pt-pt\/#website","url":"https:\/\/www.intarcon.com\/pt-pt\/","name":"INTARCON","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intarcon.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt"},{"@type":"Person","@id":"https:\/\/www.intarcon.com\/pt-pt\/#\/schema\/person\/3953ab26cc806bd58bd91f8a62054c03","name":"INTARCON","image":{"@type":"ImageObject","inLanguage":"pt","@id":"https:\/\/secure.gravatar.com\/avatar\/15e7dea3e8aff0fc73c1fbe5156ed313f6044f5727ad9a8c9752574cacdce03d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/15e7dea3e8aff0fc73c1fbe5156ed313f6044f5727ad9a8c9752574cacdce03d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/15e7dea3e8aff0fc73c1fbe5156ed313f6044f5727ad9a8c9752574cacdce03d?s=96&d=mm&r=g","caption":"INTARCON"}}]}},"_links":{"self":[{"href":"https:\/\/www.intarcon.com\/pt-pt\/wp-json\/wp\/v2\/posts\/76958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intarcon.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.intarcon.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.intarcon.com\/pt-pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.intarcon.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=76958"}],"version-history":[{"count":0,"href":"https:\/\/www.intarcon.com\/pt-pt\/wp-json\/wp\/v2\/posts\/76958\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intarcon.com\/pt-pt\/wp-json\/wp\/v2\/media\/73213"}],"wp:attachment":[{"href":"https:\/\/www.intarcon.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=76958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.intarcon.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=76958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.intarcon.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=76958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}