{"id":77061,"date":"2020-01-10T14:00:45","date_gmt":"2020-01-10T12:00:45","guid":{"rendered":"https:\/\/www.intarcon.com\/refrigeracion-con-co2\/"},"modified":"2023-09-06T16:52:48","modified_gmt":"2023-09-06T14:52:48","slug":"co2-kuhlung","status":"publish","type":"post","link":"https:\/\/www.intarcon.com\/de\/co2-kuhlung\/","title":{"rendered":"CO2-K\u00fchlung"},"content":{"rendered":"<p>Aufgrund wachsender Bef\u00fcrchtungen \u00fcber <strong>die sch\u00e4dlichen Auswirkungen fluorierter K\u00e4ltemittel auf die Umwelt<\/strong> haben nat\u00fcrliche K\u00e4ltemittel eine neue Renaissance erlebt, insbesondere <a href=\"https:\/\/www.intarcon.com\/de\/naturliche-ersatzkaltemittel\/#Dioxido_de_Carbono_CO2_R-744\">CO2<\/a>&#8211; und NH3-K\u00e4lte, die f\u00fcr industrielle Zwecke bei niedrigen Temperaturen eingesetzt werden.<\/p>\n<p>Kohlendioxid (CO2) ist als K\u00e4ltemittel unter der Bezeichnung <strong>R-744<\/strong> bekannt und hat sich in j\u00fcngster Zeit zu einem der beliebtesten nat\u00fcrlichen K\u00e4ltemittel entwickelt, obwohl die Technologie nicht neu ist, da sie bereits vor mehr als einem Jahrhundert verwendet wurde.<br \/>\nSeine j\u00fcngste Beliebtheit als K\u00e4ltemittel ist auf seine <strong>sehr geringen Auswirkungen auf die Umwelt<\/strong> im Vergleich zu den HFCs (Fluorkohlenwasserstoffen) zur\u00fcckzuf\u00fchren, die durch die derzeitigen Vorschriften stark bedroht sind (F-Gas).<\/p>\n<p>CO2 sch\u00e4digt die Ozonschicht nicht (Ozonabbaupotenzial ODP = 0) und hat <strong>einen geringen Einfluss auf die globale Erw\u00e4rmung<\/strong> (Treibhauspotenzial GWP = 1), wobei der letztgenannte Wert als Referenz f\u00fcr die Bestimmung des GWP anderer Gase gilt. Dar\u00fcber hinaus tr\u00e4gt dieses Gas aufgrund seines hohen Wirkungsgrades auch indirekt weniger zur globalen Erw\u00e4rmung bei.<\/p>\n<h2>Was ist CO2?<\/h2>\n<p>CO2 ist eine geruchlose, farblose Fl\u00fcssigkeit, die schwerer als Luft ist. Obwohl es f\u00fcr das Leben auf der Erde notwendig ist, ist es auch ein Treibhausgas (THG), das die Umwelt ver\u00e4ndern kann, wenn seine Konzentration in der Atmosph\u00e4re deutlich zunimmt. Es ist ein &#8220;<strong>hochsicheres<\/strong>&#8221; K\u00e4ltemittel (Gruppe L1 nach RSIF), d. h. &#8220;<strong>nicht entflammbar<\/strong>&#8221; und &#8220;<strong>wenig toxisch<\/strong>&#8220;.<\/p>\n<p>CO2 wurde bereits vor dem Aufkommen der Freone als K\u00e4ltemittel verwendet, kam aber aufgrund seiner gr\u00f6\u00dferen technologischen Komplexit\u00e4t schnell au\u00dfer Gebrauch. Es hat <strong>hervorragende thermophysikalische Eigenschaften<\/strong>, obwohl es aufgrund seiner niedrigen kritischen Temperatur (30,978 \u00b0C) und der hohen Dr\u00fccke Schwierigkeiten bereitet. Es hat eine viel h\u00f6here volumetrische Kapazit\u00e4t als herk\u00f6mmliche K\u00e4ltemittel.<\/p>\n<p>Dieses Gas hat eine hohe W\u00e4rmeleitf\u00e4higkeit und eine hohe Dichte in der Gasphase, was zu einer guten W\u00e4rme\u00fcbertragung in Verdampfern, Kondensatoren und Gask\u00fchlern f\u00fchrt; diese Eigenschaften erm\u00f6glichen die Auswahl kleinerer Ger\u00e4te im Vergleich zu denen, die FCKW, HFCKW und HFKW verwenden. Da es einen geringen Druckabfall hat, kann der Durchmesser der Rohrleitungen verringert werden.<\/p>\n<h2>CO2, eine gute Alternative f\u00fcr die K\u00fchlung<\/h2>\n<p><a href=\"https:\/\/www.intarcon.com\/de\/naturliche-ersatzkaltemittel\/\">CO2 ist sowohl f\u00fcr die gewerbliche als auch f\u00fcr die industrielle K\u00fchlung eine gute Alternative,<\/a> wobei jedoch bestimmte Sicherheitsvorkehrungen zu beachten sind. Es ist zu bedenken, dass CO2 geruchlich nicht wahrnehmbar ist und, da es dichter als Luft ist, den Sauerstoff in einem gesundheitssch\u00e4dlichen Ausma\u00df verdr\u00e4ngen kann. Da es keinen Geruch abgibt, kann es dazu f\u00fchren, dass der Techniker ein eventuelles Leck nicht entdecken kann. Diese Eigenschaften zwingen uns, der Lecksuche besondere Aufmerksamkeit zu widmen, ein Alarmsystem zu haben, das das Vorhandensein von CO2 rechtzeitig erkennt und warnt, und ein Notl\u00fcftungssystem zu haben.<\/p>\n<p>Andererseits f\u00fchrt der hohe Druck des Gases beim Entweichen zu einem Ausbruch von spritzendem K\u00e4ltemittel mit festen R\u00fcckst\u00e4nden bei sehr niedriger Temperatur und Schallgeschwindigkeit. Es ist wichtig zu wissen, dass CO2 niemals in fl\u00fcssigem Zustand eingef\u00fcllt werden sollte, wenn das System unter dem Tripelpunktsdruck (5,2 bar) liegt, da sonst die in das System eintretende Fl\u00fcssigkeit pl\u00f6tzlich ihren Zustand in Trockeneis \u00e4ndert und in diesem Zustand im System verbleibt.<\/p>\n<p>Im Gegensatz zu anderen nat\u00fcrlichen K\u00e4ltemitteln kann <strong>CO2 nicht in alte oder neue Anlagen nachger\u00fcstet werden.<\/strong> Die Anlagen m\u00fcssen f\u00fcr die Eigenschaften dieses Gases und f\u00fcr die hohen Dr\u00fccke, denen es standhalten muss, ausgelegt sein. Schlie\u00dflich hat CO2 gegen\u00fcber den Kohlenwasserstoffen den Vorteil, dass es in Anlagen ohne Lastbegrenzung eingesetzt werden kann.<\/p>\n<p><a href=\"https:\/\/www.intarcon.com\/de\/die-nachhaltige-zukunft-der-kalteerzeugung-warum-r744-oder-co2\/\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-79916\" src=\"https:\/\/www.intarcon.com\/wp-content\/uploads\/2020\/01\/cta-cp-de-r744-o-co2.webp\" alt=\"Die nachhaltige Zukunft der K\u00e4lteerzeugung, warum R744 oder CO2? INTARCON\" width=\"1204\" height=\"347\" srcset=\"https:\/\/www.intarcon.com\/wp-content\/uploads\/2020\/01\/cta-cp-de-r744-o-co2.webp 1204w, https:\/\/www.intarcon.com\/wp-content\/uploads\/2020\/01\/cta-cp-de-r744-o-co2-768x221.webp 768w, https:\/\/www.intarcon.com\/wp-content\/uploads\/2020\/01\/cta-cp-de-r744-o-co2-640x184.webp 640w, https:\/\/www.intarcon.com\/wp-content\/uploads\/2020\/01\/cta-cp-de-r744-o-co2-400x115.webp 400w, https:\/\/www.intarcon.com\/wp-content\/uploads\/2020\/01\/cta-cp-de-r744-o-co2-367x106.webp 367w, https:\/\/www.intarcon.com\/wp-content\/uploads\/2020\/01\/cta-cp-de-r744-o-co2-600x173.webp 600w\" sizes=\"(max-width: 1204px) 100vw, 1204px\" \/><\/a><\/p>\n<h2>Was ist die Geschichte von CO2 als K\u00e4ltemittel?<\/h2>\n<p>CO2 ist seit Anbeginn der Menschheit bekannt und existiert in der Atmosph\u00e4re in einer Konzentration von 0,04 Volumenprozent.<br \/>\nAls K\u00e4ltemittel wurde es bereits im 19. Jahrhundert in der mechanischen K\u00e4ltetechnik eingesetzt. Im Jahr 1881 baute Carl Linde die erste Maschine, die CO2 verwendete. In der Folge wurden Kompressoren entwickelt, die mit CO2 arbeiten, und es wurden zweistufige Systeme entwickelt. Die Verwendung von CO2 wurde immer weiter verbreitet.<br \/>\nNach dem Ersten Weltkrieg wurden synthetische Gase entwickelt, die den Einsatz von weniger robusten und effizienteren Elementen erm\u00f6glichten. Damit begann der Niedergang von CO2 als K\u00e4ltemittel, und die FCKW-Gase gewannen den Kampf. 50 Jahre lang beherrschten FCKW-K\u00e4ltemittel den Weltmarkt, bis 1974 entdeckt wurde, dass die Verwendung dieser Stoffe ein Ozonloch verursachte. Dies war die Geburtsstunde der FKW-K\u00e4ltemittel, die bis heute verwendet werden, die aber die globale Erw\u00e4rmung beeintr\u00e4chtigen und deren Verwendung daher eingeschr\u00e4nkt ist.<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-77063 aligncenter\" src=\"https:\/\/www.intarcon.com\/wp-content\/uploads\/2020\/01\/5-de-refrigeracion-con-co2.webp\" alt=\"CO2-K\u00fchlung - INTARCON\" width=\"593\" height=\"300\" srcset=\"https:\/\/www.intarcon.com\/wp-content\/uploads\/2020\/01\/5-de-refrigeracion-con-co2.webp 593w, https:\/\/www.intarcon.com\/wp-content\/uploads\/2020\/01\/5-de-refrigeracion-con-co2-400x202.webp 400w, https:\/\/www.intarcon.com\/wp-content\/uploads\/2020\/01\/5-de-refrigeracion-con-co2-367x186.webp 367w\" sizes=\"(max-width: 593px) 100vw, 593px\" \/><\/p>\n<h2>Warum erw\u00e4gen wir den Einsatz von CO2 in K\u00fchlsystemen?<\/h2>\n<p>Das von der Klimarahmenkonvention der Vereinten Nationen vereinbarte <strong>Kyoto-Protokoll<\/strong> hat zum Ziel, die Emissionen von sechs Treibhausgasen (CO2, CH4, N2O, HFC, PFC und SF6) zu reduzieren.<br \/>\n<img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.intarcon.com\/wp-content\/uploads\/2020\/01\/Refrigeraci\u00f3n-con-CO2.1.jpg\" alt=\"\" width=\"600\" height=\"348\" \/><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-77068 aligncenter\" src=\"https:\/\/www.intarcon.com\/wp-content\/uploads\/2020\/01\/2-de-refrigeracion-con-co2.webp\" alt=\"CO2-K\u00fchlung - INTARCON\" width=\"220\" height=\"113\" \/><br \/>\nZu den Ma\u00dfnahmen und Verordnungen, die zur Erreichung dieser Ziele erlassen wurden, geh\u00f6rt die F-Gas-Verordnung, die 2006 eingef\u00fchrt und in der Folge immer wieder versch\u00e4rft wurde. Ihr Ziel ist es, die FKW-Gasemissionen bis 2030 um ein Drittel zu reduzieren.<br \/>\nUm diese Ziele zu erreichen, werden auf europ\u00e4ischer Ebene Verwendungsbeschr\u00e4nkungen und Verbote festgelegt. Gleichzeitig werden auf staatlicher Ebene Steuern auf die Verwendung von K\u00e4ltemitteln festgelegt, um die Verwendung anderer K\u00e4ltemittel mit geringeren Umweltauswirkungen zu f\u00f6rdern.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\" wp-image-77073 aligncenter\" src=\"https:\/\/www.intarcon.com\/wp-content\/uploads\/2020\/01\/3-de-refrigeracion-con-co2.webp\" alt=\"CO2-K\u00fchlung - INTARCON\" width=\"838\" height=\"338\" \/><br \/>\nWenn wir uns auf K\u00e4ltemittel mit GWP-Werten &lt; 150 konzentrieren, sind die meisten von ihnen entflammbar (HFO), giftig (NH3) oder arbeiten mit hohen Dr\u00fccken (CO2).<\/p>\n<h3><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-77078 aligncenter\" src=\"https:\/\/www.intarcon.com\/wp-content\/uploads\/2020\/01\/4-de-refrigeracion-con-co2.webp\" alt=\"CO2-K\u00fchlung - INTARCON\" width=\"714\" height=\"190\" srcset=\"https:\/\/www.intarcon.com\/wp-content\/uploads\/2020\/01\/4-de-refrigeracion-con-co2.webp 714w, https:\/\/www.intarcon.com\/wp-content\/uploads\/2020\/01\/4-de-refrigeracion-con-co2-640x170.webp 640w, https:\/\/www.intarcon.com\/wp-content\/uploads\/2020\/01\/4-de-refrigeracion-con-co2-400x106.webp 400w, https:\/\/www.intarcon.com\/wp-content\/uploads\/2020\/01\/4-de-refrigeracion-con-co2-367x98.webp 367w, https:\/\/www.intarcon.com\/wp-content\/uploads\/2020\/01\/4-de-refrigeracion-con-co2-600x160.webp 600w\" sizes=\"(max-width: 714px) 100vw, 714px\" \/><\/p>\n<h3>Thermodynamische Eigenschaften von CO2<\/h3>\n<p><strong>Der Hauptunterschied zwischen CO2<\/strong> und anderen K\u00e4ltemitteln ist der Betriebsdruck, bei dem es arbeitet. Dies macht es jedoch zu einem Gas mit <strong>hoher Dichte<\/strong>, wodurch eine<strong> h\u00f6here K\u00e4lteleistung<\/strong> bei geringer zirkulierender Masse erreicht wird.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-77083 aligncenter\" src=\"https:\/\/www.intarcon.com\/wp-content\/uploads\/2020\/01\/6-de-refrigeracion-con-co2.webp\" alt=\"CO2-K\u00fchlung - INTARCON\" width=\"365\" height=\"287\" \/><\/p>\n<p><strong>Die Verdampfungsenthalpie pro verdr\u00e4ngtem Kubikmeter (kJ\/m3)<\/strong> ist viel h\u00f6her als bei anderen Gasen. Dies bedeutet, dass der Verdr\u00e4ngungsraum des Kompressors und der Rohrdurchmesser kleiner sind.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-77088 aligncenter\" src=\"https:\/\/www.intarcon.com\/wp-content\/uploads\/2020\/01\/7-de-refrigeracion-con-co2.webp\" alt=\"CO2-K\u00fchlung - INTARCON\" width=\"446\" height=\"332\" \/><\/p>\n<h4><\/h4>\n<h4>Druck-Enthalpie-Diagramm (log P-h) (Mollier-Diagramm)<\/h4>\n<p>Bei der Arbeit mit CO2 f\u00fcr die K\u00e4lteerzeugung m\u00fcssen wir ein erweitertes P-h-Diagramm verwenden, d. h. zus\u00e4tzlich zu den \u00fcblichen Dampf-, Dampf-Fl\u00fcssigkeits- und Fl\u00fcssigkeitszonen, die im Mollier-Diagramm jedes herk\u00f6mmlichen K\u00e4ltemittels zu sehen sind, m\u00fcssen wir auch die Zone oberhalb des kritischen Punktes (\u00fcberkritische Phase) sowie die Zonen unterhalb des Tripelpunktes darstellen.<\/p>\n<p>Die folgende Grafik zeigt den physikalischen Zustand von CO2 in Abh\u00e4ngigkeit von Druck (P) und Enthalpie (h). Durch Ver\u00e4nderung dieser beiden Variablen erh\u00e4lt man vier klar differenzierte Phasen:<strong> fest, fl\u00fcssig, dampff\u00f6rmig und \u00fcberkritisches Fluid<\/strong>; dazu kommen drei weitere Zweiphasen-Mischzonen:<strong> fest-fl\u00fcssig, fest-dampff\u00f6rmig und fl\u00fcssig-dampff\u00f6rmig.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-77093 aligncenter\" src=\"https:\/\/www.intarcon.com\/wp-content\/uploads\/2020\/01\/8-de-refrigeracion-con-co2.webp\" alt=\"CO2-K\u00fchlung - INTARCON\" width=\"460\" height=\"412\" \/><\/p>\n<p>Im Vergleich zu anderen K\u00e4ltemitteln f\u00e4llt auf, dass schon bei sehr niedrigen Temperaturen hohe S\u00e4ttigungsdr\u00fccke erreicht werden (z. B. 0 \u00b0C \u27f9 35 bar). Die folgenden Punkte im Phasendiagramm sollten beachtet werden:<\/p>\n<ul>\n<li style=\"font-weight: 400;\"><strong>Kritischer Punkt:<\/strong> 30,98 \u00b0C und 73,77 bar \u27f9 Phasenwechsel ohne Kondensation.<\/li>\n<li style=\"font-weight: 400;\"><strong>Tripelpunkt:<\/strong> -56,56 \u00b0C und 5,187 bar \u27f9 Die fl\u00fcssige Phase kann nur bei einem Druck von \u00fcber 5,187 bar existieren, dann entsteht bei der Ausdehnung der Fl\u00fcssigkeit bei einem niedrigeren Druck Trockeneis (fest).<\/li>\n<\/ul>\n<h4>Mollier-Diagramm f\u00fcr typische K\u00fchlanwendungen<\/h4>\n<p>\u00dcblicherweise wird zur Darstellung von K\u00e4ltemaschinenkreisl\u00e4ufen ein vereinfachtes Mollier-Diagramm verwendet, in dem weder der Bereich mit Feststoff oder Fest-Fl\u00fcssig (linke Seite) noch der Bereich unterhalb des Tripelpunkts (&lt; 5,2 bar) dargestellt ist. Daher w\u00fcrde das Diagramm f\u00fcr den normalen K\u00e4lteeinsatz nur durch die Zonen mit Fl\u00fcssigkeit und Dampf (oder Fl\u00fcssig-Dampf) dargestellt, ganz \u00e4hnlich wie das Diagramm f\u00fcr jedes andere K\u00e4ltemittel im t\u00e4glichen Gebrauch, aber mit viel h\u00f6heren Dr\u00fccken:<\/p>\n<h4><b><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.intarcon.com\/wp-content\/uploads\/2020\/01\/Refrigeraci\u00f3n-con-CO2.9.jpg\" alt=\"Refrigeraci\u00f3n con CO2\" width=\"605\" height=\"407\" \/><\/b><\/h4>\n<h4>Was passiert in der kritischen Region?<\/h4>\n<p>Wenn man sich dem kritischen Punkt n\u00e4hert, tendieren die Dichten von Fl\u00fcssigkeit und Dampf zum gleichen Wert, und der Unterschied zwischen Fl\u00fcssigkeit und Dampf verschwindet, wenn der kritische Punkt erreicht ist. Es entsteht ein Bereich mit hoher Dichte.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-77098 aligncenter\" src=\"https:\/\/www.intarcon.com\/wp-content\/uploads\/2020\/01\/10-de-refrigeracion-con-co2.webp\" alt=\"CO2-K\u00fchlung - INTARCON\" width=\"467\" height=\"268\" \/><\/p>\n<p>Die Tatsache, dass wir unterhalb des kritischen Punktes arbeiten k\u00f6nnen oder nicht, bestimmt die Art der Anlage und die Betriebsweise, wodurch wir v\u00f6llig unterschiedliche Systeme erhalten. In luftgek\u00fchlten K\u00e4lteanlagen k\u00f6nnen wir bei Umgebungstemperaturen unter ca. 25 \u00b0C in einem <a href=\"https:\/\/www.intarcon.com\/en\/subcritical-co2-refrigeration\/\">unterkritischen Kreislauf<\/a> arbeiten, w\u00e4hrend wir bei h\u00f6heren Temperaturen in einem <a href=\"https:\/\/www.intarcon.com\/en\/transcritical-co2-refrigeration\/\">transkritischen Kreislauf<\/a> arbeiten m\u00fcssen.<\/p>\n<h2>Die h\u00e4ufigsten Anwendungen, Vorteile, Nachteile und Vorschriften f\u00fcr CO2 als K\u00e4ltemittel.<\/h2>\n<h3>Die h\u00e4ufigsten Anwendungen der CO2-K\u00e4lte.<\/h3>\n<ul>\n<li style=\"font-weight: 400;\">Gewerbliche und industrielle K\u00e4ltetechnik.<\/li>\n<li style=\"font-weight: 400;\">Gek\u00fchlter Transport.<\/li>\n<li style=\"font-weight: 400;\">Kompakte Systeme.<\/li>\n<li style=\"font-weight: 400;\">In Superm\u00e4rkten.<\/li>\n<li style=\"font-weight: 400;\">Und zwar in direkten, kaskadierten und indirekten Systemen.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.intarcon.com\/en\/natural-refrigerant-applications\/\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-59929 aligncenter\" src=\"https:\/\/www.intarcon.com\/wp-content\/uploads\/2021\/09\/cta-ce-aplicaciones-con-refrigerantes-en-1204-x-347-px.jpg\" alt=\"\" width=\"1204\" height=\"347\" srcset=\"https:\/\/www.intarcon.com\/wp-content\/uploads\/2021\/09\/cta-ce-aplicaciones-con-refrigerantes-en-1204-x-347-px.jpg 1204w, https:\/\/www.intarcon.com\/wp-content\/uploads\/2021\/09\/cta-ce-aplicaciones-con-refrigerantes-en-1204-x-347-px-768x221.jpg 768w, https:\/\/www.intarcon.com\/wp-content\/uploads\/2021\/09\/cta-ce-aplicaciones-con-refrigerantes-en-1204-x-347-px-640x184.jpg 640w, https:\/\/www.intarcon.com\/wp-content\/uploads\/2021\/09\/cta-ce-aplicaciones-con-refrigerantes-en-1204-x-347-px-400x115.jpg 400w, https:\/\/www.intarcon.com\/wp-content\/uploads\/2021\/09\/cta-ce-aplicaciones-con-refrigerantes-en-1204-x-347-px-367x106.jpg 367w, https:\/\/www.intarcon.com\/wp-content\/uploads\/2021\/09\/cta-ce-aplicaciones-con-refrigerantes-en-1204-x-347-px-600x173.jpg 600w\" sizes=\"(max-width: 1204px) 100vw, 1204px\" \/><\/a><\/p>\n<h3>Vorteile der Verwendung von CO2 als K\u00e4ltemittel.<\/h3>\n<ul>\n<li style=\"font-weight: 400;\">Ozonabbaupotenzial (ODP) = 0, Erderw\u00e4rmungspotenzial (GWP) = 1.<\/li>\n<li style=\"font-weight: 400;\"><strong>Nicht entflammbar.<\/strong><\/li>\n<li style=\"font-weight: 400;\">Es hat eine <strong>geringe Toxizit\u00e4t<\/strong> (nur in hohen Konzentrationen gef\u00e4hrlich).<\/li>\n<li style=\"font-weight: 400;\">Enth\u00e4lt einen <strong>hohen W\u00e4rme\u00fcbergangskoeffizienten.<\/strong><\/li>\n<li style=\"font-weight: 400;\"><strong>Hohe Leistung,<\/strong> niedriger Energieverbrauch.<\/li>\n<li style=\"font-weight: 400;\">Es hat<strong> keine Langzeitnebenwirkungen.<\/strong><\/li>\n<li style=\"font-weight: 400;\">Sie <strong>ist wirtschaftlich<\/strong> und birgt kein Risiko der Veralterung.<\/li>\n<li style=\"font-weight: 400;\"><strong>Hohe Verf\u00fcgbarkeit<\/strong>, da es als Nebenprodukt verschiedener Prozesse gewonnen wird.<\/li>\n<li style=\"font-weight: 400;\">Kann mit POE-, PGA- und PVE-Schmierstoffen gemischt werden.<\/li>\n<\/ul>\n<h3>Nachteile der Verwendung von CO2 als K\u00e4ltemittel.<\/h3>\n<ul>\n<li style=\"font-weight: 400;\">Es funktioniert bei h\u00f6heren Temperaturen und Dr\u00fccken als HFKW und andere K\u00e4ltemittel.<\/li>\n<li style=\"font-weight: 400;\">Im Falle einer Leckage sammelt sich das CO2 am Boden und verdr\u00e4ngt die Luft; da es geruchlos ist, kann es olfaktorisch nicht wahrgenommen werden.<\/li>\n<li style=\"font-weight: 400;\">CO2 ist nur f\u00fcr neue Anlagen geeignet. Als Hochdruckk\u00e4ltemittel mit niedriger kritischer Temperatur ist es nicht f\u00fcr die Nachr\u00fcstung von Anlagen mit bestehenden fluorierten K\u00e4ltemitteln geeignet.<\/li>\n<li style=\"font-weight: 400;\">Der Preis des Systems ist hoch.<\/li>\n<\/ul>\n<h3>Die bei der CO2-K\u00fchlung zu ber\u00fccksichtigenden Vorschriften.<\/h3>\n<ul>\n<li style=\"font-weight: 400;\">Verordnung (EG) Nr. 1005\/2009 des Europ\u00e4ischen Parlaments \u00fcber Stoffe, die zum Abbau der Ozonschicht f\u00fchren.<\/li>\n<li style=\"font-weight: 400;\">K\u00f6niglicher Erlass 552\/2019 vom 27. September zur Verabschiedung der Sicherheitsvorschriften f\u00fcr K\u00e4lteanlagen und ihrer erg\u00e4nzenden technischen Anweisungen.<\/li>\n<li style=\"font-weight: 400;\">K\u00f6niglicher Erlass 1042\/2013 vom 27. Dezember zur Genehmigung der Verordnung \u00fcber die Steuer auf fluorierte Treibhausgase. Gesetz 16\/2013.<\/li>\n<li style=\"font-weight: 400;\">Gesetz 6\/2018, vom 3. Juli, \u00fcber den allgemeinen Staatshaushalt 2018. Artikel 85 (\u00c4nderung der vorherigen Verordnung).<\/li>\n<li style=\"font-weight: 400;\">Verordnung (EU) Nr. 517\/2014 des Europ\u00e4ischen Parlaments und des Rates vom 16. April 2014 \u00fcber fluorierte Treibhausgase. &#8220;F-Gas-Verordnung&#8221;.<\/li>\n<li style=\"font-weight: 400;\">K\u00f6niglicher Erlass 115\/2017 vom 17. Februar, der das Inverkehrbringen und die Handhabung von fluorierten Gasen und Ausr\u00fcstungen, die auf diesen basieren, sowie die Zertifizierung von Fachleuten, die diese verwenden, regelt und die technischen Anforderungen f\u00fcr Anlagen festlegt, die T\u00e4tigkeiten ausf\u00fchren, bei denen fluorierte Gase freigesetzt werden.<\/li>\n<li style=\"font-weight: 400;\">Internationales Elektrotechnisches Komitee (IEC 60335-2-89). K\u00e4ltemittelf\u00fcllung in gek\u00fchlten M\u00f6beln.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.intarcon.com\/de\/technische-beratung\/\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-68608 aligncenter\" src=\"https:\/\/www.intarcon.com\/wp-content\/uploads\/2022\/07\/CTA-Solicitar-Asesoria-DE.webp\" alt=\"Technische Beratung anfordern - INTARCON\" width=\"1191\" height=\"347\" srcset=\"https:\/\/www.intarcon.com\/wp-content\/uploads\/2022\/07\/CTA-Solicitar-Asesoria-DE.webp 1191w, https:\/\/www.intarcon.com\/wp-content\/uploads\/2022\/07\/CTA-Solicitar-Asesoria-DE-768x224.webp 768w, https:\/\/www.intarcon.com\/wp-content\/uploads\/2022\/07\/CTA-Solicitar-Asesoria-DE-640x186.webp 640w, https:\/\/www.intarcon.com\/wp-content\/uploads\/2022\/07\/CTA-Solicitar-Asesoria-DE-400x117.webp 400w, https:\/\/www.intarcon.com\/wp-content\/uploads\/2022\/07\/CTA-Solicitar-Asesoria-DE-367x107.webp 367w, https:\/\/www.intarcon.com\/wp-content\/uploads\/2022\/07\/CTA-Solicitar-Asesoria-DE-600x175.webp 600w\" sizes=\"(max-width: 1191px) 100vw, 1191px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aufgrund wachsender Bef\u00fcrchtungen \u00fcber die sch\u00e4dlichen Auswirkungen fluorierter K\u00e4ltemittel auf die Umwelt haben nat\u00fcrliche K\u00e4ltemittel eine neue Renaissance erlebt, insbesondere CO2&#8211; und NH3-K\u00e4lte, die f\u00fcr industrielle Zwecke bei niedrigen Temperaturen eingesetzt werden. Kohlendioxid (CO2) ist als K\u00e4ltemittel unter der Bezeichnung R-744 bekannt und hat sich in j\u00fcngster Zeit zu einem der beliebtesten nat\u00fcrlichen K\u00e4ltemittel entwickelt, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":58154,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[642],"tags":[],"class_list":["post-77061","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kuhlende-gase"],"featured_image_src":{"landsacpe":["https:\/\/www.intarcon.com\/wp-content\/uploads\/2020\/01\/Cabecera-Refrigeraci\u00f3n_CO2_EN-rasgado.jpg",792,445,false],"list":["https:\/\/www.intarcon.com\/wp-content\/uploads\/2020\/01\/Cabecera-Refrigeraci\u00f3n_CO2_EN-rasgado-463x348.jpg",463,348,true],"medium":["https:\/\/www.intarcon.com\/wp-content\/uploads\/2020\/01\/Cabecera-Refrigeraci\u00f3n_CO2_EN-rasgado.jpg",792,445,false],"full":["https:\/\/www.intarcon.com\/wp-content\/uploads\/2020\/01\/Cabecera-Refrigeraci\u00f3n_CO2_EN-rasgado.jpg",792,445,false]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CO2-K\u00fchlung - INTARCON<\/title>\n<meta name=\"description\" content=\"Die CO2-K\u00fchlung ist eine gute Alternative, die unserer Umwelt, der Ozonschicht und der globalen Erw\u00e4rmung nicht schadet.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.intarcon.com\/de\/co2-kuhlung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CO2-K\u00fchlung - INTARCON\" \/>\n<meta property=\"og:description\" content=\"Die CO2-K\u00fchlung ist eine gute Alternative, die unserer Umwelt, der Ozonschicht und der globalen Erw\u00e4rmung nicht schadet.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.intarcon.com\/de\/co2-kuhlung\/\" \/>\n<meta property=\"og:site_name\" content=\"INTARCON\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/intarcon\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-10T12:00:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-06T14:52:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.intarcon.com\/wp-content\/uploads\/2020\/01\/Cabecera-Refrigeraci\u00f3n_CO2_EN-rasgado.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"792\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"INTARCON\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"INTARCON\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.intarcon.com\\\/de\\\/co2-kuhlung\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.intarcon.com\\\/de\\\/co2-kuhlung\\\/\"},\"author\":{\"name\":\"INTARCON\",\"@id\":\"https:\\\/\\\/www.intarcon.com\\\/de\\\/#\\\/schema\\\/person\\\/2191d1cc4858aa786ac48fb8990feb40\"},\"headline\":\"CO2-K\u00fchlung\",\"datePublished\":\"2020-01-10T12:00:45+00:00\",\"dateModified\":\"2023-09-06T14:52:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.intarcon.com\\\/de\\\/co2-kuhlung\\\/\"},\"wordCount\":1710,\"publisher\":{\"@id\":\"https:\\\/\\\/www.intarcon.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.intarcon.com\\\/de\\\/co2-kuhlung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.intarcon.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Cabecera-Refrigeraci\u00f3n_CO2_EN-rasgado.jpg\",\"articleSection\":[\"K\u00fchlende Gase\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.intarcon.com\\\/de\\\/co2-kuhlung\\\/\",\"url\":\"https:\\\/\\\/www.intarcon.com\\\/de\\\/co2-kuhlung\\\/\",\"name\":\"CO2-K\u00fchlung - INTARCON\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.intarcon.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.intarcon.com\\\/de\\\/co2-kuhlung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.intarcon.com\\\/de\\\/co2-kuhlung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.intarcon.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Cabecera-Refrigeraci\u00f3n_CO2_EN-rasgado.jpg\",\"datePublished\":\"2020-01-10T12:00:45+00:00\",\"dateModified\":\"2023-09-06T14:52:48+00:00\",\"description\":\"Die CO2-K\u00fchlung ist eine gute Alternative, die unserer Umwelt, der Ozonschicht und der globalen Erw\u00e4rmung nicht schadet.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.intarcon.com\\\/de\\\/co2-kuhlung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.intarcon.com\\\/de\\\/co2-kuhlung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.intarcon.com\\\/de\\\/co2-kuhlung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.intarcon.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Cabecera-Refrigeraci\u00f3n_CO2_EN-rasgado.jpg\",\"contentUrl\":\"https:\\\/\\\/www.intarcon.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Cabecera-Refrigeraci\u00f3n_CO2_EN-rasgado.jpg\",\"width\":792,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.intarcon.com\\\/de\\\/co2-kuhlung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.intarcon.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"K\u00fchlende Gase\",\"item\":\"https:\\\/\\\/www.intarcon.com\\\/de\\\/category\\\/kuhlende-gase\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CO2-K\u00fchlung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.intarcon.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.intarcon.com\\\/de\\\/\",\"name\":\"INTARCON\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.intarcon.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.intarcon.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.intarcon.com\\\/de\\\/#organization\",\"name\":\"INTARCON\",\"url\":\"https:\\\/\\\/www.intarcon.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.intarcon.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.intarcon.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo-intarcon-adaptado.jpg\",\"contentUrl\":\"https:\\\/\\\/www.intarcon.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo-intarcon-adaptado.jpg\",\"width\":563,\"height\":750,\"caption\":\"INTARCON\"},\"image\":{\"@id\":\"https:\\\/\\\/www.intarcon.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/intarcon\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/intarcon\\\/\",\"https:\\\/\\\/www.instagram.com\\\/intarcon_refrigeracion\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.intarcon.com\\\/de\\\/#\\\/schema\\\/person\\\/2191d1cc4858aa786ac48fb8990feb40\",\"name\":\"INTARCON\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/15e7dea3e8aff0fc73c1fbe5156ed313f6044f5727ad9a8c9752574cacdce03d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/15e7dea3e8aff0fc73c1fbe5156ed313f6044f5727ad9a8c9752574cacdce03d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/15e7dea3e8aff0fc73c1fbe5156ed313f6044f5727ad9a8c9752574cacdce03d?s=96&d=mm&r=g\",\"caption\":\"INTARCON\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CO2-K\u00fchlung - INTARCON","description":"Die CO2-K\u00fchlung ist eine gute Alternative, die unserer Umwelt, der Ozonschicht und der globalen Erw\u00e4rmung nicht schadet.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.intarcon.com\/de\/co2-kuhlung\/","og_locale":"de_DE","og_type":"article","og_title":"CO2-K\u00fchlung - INTARCON","og_description":"Die CO2-K\u00fchlung ist eine gute Alternative, die unserer Umwelt, der Ozonschicht und der globalen Erw\u00e4rmung nicht schadet.","og_url":"https:\/\/www.intarcon.com\/de\/co2-kuhlung\/","og_site_name":"INTARCON","article_publisher":"https:\/\/www.facebook.com\/intarcon\/","article_published_time":"2020-01-10T12:00:45+00:00","article_modified_time":"2023-09-06T14:52:48+00:00","og_image":[{"width":792,"height":445,"url":"https:\/\/www.intarcon.com\/wp-content\/uploads\/2020\/01\/Cabecera-Refrigeraci\u00f3n_CO2_EN-rasgado.jpg","type":"image\/jpeg"}],"author":"INTARCON","twitter_card":"summary_large_image","twitter_misc":{"Written by":"INTARCON","Est. reading time":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.intarcon.com\/de\/co2-kuhlung\/#article","isPartOf":{"@id":"https:\/\/www.intarcon.com\/de\/co2-kuhlung\/"},"author":{"name":"INTARCON","@id":"https:\/\/www.intarcon.com\/de\/#\/schema\/person\/2191d1cc4858aa786ac48fb8990feb40"},"headline":"CO2-K\u00fchlung","datePublished":"2020-01-10T12:00:45+00:00","dateModified":"2023-09-06T14:52:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.intarcon.com\/de\/co2-kuhlung\/"},"wordCount":1710,"publisher":{"@id":"https:\/\/www.intarcon.com\/de\/#organization"},"image":{"@id":"https:\/\/www.intarcon.com\/de\/co2-kuhlung\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intarcon.com\/wp-content\/uploads\/2020\/01\/Cabecera-Refrigeraci\u00f3n_CO2_EN-rasgado.jpg","articleSection":["K\u00fchlende Gase"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.intarcon.com\/de\/co2-kuhlung\/","url":"https:\/\/www.intarcon.com\/de\/co2-kuhlung\/","name":"CO2-K\u00fchlung - INTARCON","isPartOf":{"@id":"https:\/\/www.intarcon.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.intarcon.com\/de\/co2-kuhlung\/#primaryimage"},"image":{"@id":"https:\/\/www.intarcon.com\/de\/co2-kuhlung\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intarcon.com\/wp-content\/uploads\/2020\/01\/Cabecera-Refrigeraci\u00f3n_CO2_EN-rasgado.jpg","datePublished":"2020-01-10T12:00:45+00:00","dateModified":"2023-09-06T14:52:48+00:00","description":"Die CO2-K\u00fchlung ist eine gute Alternative, die unserer Umwelt, der Ozonschicht und der globalen Erw\u00e4rmung nicht schadet.","breadcrumb":{"@id":"https:\/\/www.intarcon.com\/de\/co2-kuhlung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.intarcon.com\/de\/co2-kuhlung\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.intarcon.com\/de\/co2-kuhlung\/#primaryimage","url":"https:\/\/www.intarcon.com\/wp-content\/uploads\/2020\/01\/Cabecera-Refrigeraci\u00f3n_CO2_EN-rasgado.jpg","contentUrl":"https:\/\/www.intarcon.com\/wp-content\/uploads\/2020\/01\/Cabecera-Refrigeraci\u00f3n_CO2_EN-rasgado.jpg","width":792,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/www.intarcon.com\/de\/co2-kuhlung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.intarcon.com\/de\/"},{"@type":"ListItem","position":2,"name":"K\u00fchlende Gase","item":"https:\/\/www.intarcon.com\/de\/category\/kuhlende-gase\/"},{"@type":"ListItem","position":3,"name":"CO2-K\u00fchlung"}]},{"@type":"WebSite","@id":"https:\/\/www.intarcon.com\/de\/#website","url":"https:\/\/www.intarcon.com\/de\/","name":"INTARCON","description":"","publisher":{"@id":"https:\/\/www.intarcon.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intarcon.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.intarcon.com\/de\/#organization","name":"INTARCON","url":"https:\/\/www.intarcon.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.intarcon.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.intarcon.com\/wp-content\/uploads\/2023\/07\/logo-intarcon-adaptado.jpg","contentUrl":"https:\/\/www.intarcon.com\/wp-content\/uploads\/2023\/07\/logo-intarcon-adaptado.jpg","width":563,"height":750,"caption":"INTARCON"},"image":{"@id":"https:\/\/www.intarcon.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/intarcon\/","https:\/\/www.linkedin.com\/company\/intarcon\/","https:\/\/www.instagram.com\/intarcon_refrigeracion\/"]},{"@type":"Person","@id":"https:\/\/www.intarcon.com\/de\/#\/schema\/person\/2191d1cc4858aa786ac48fb8990feb40","name":"INTARCON","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/15e7dea3e8aff0fc73c1fbe5156ed313f6044f5727ad9a8c9752574cacdce03d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/15e7dea3e8aff0fc73c1fbe5156ed313f6044f5727ad9a8c9752574cacdce03d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/15e7dea3e8aff0fc73c1fbe5156ed313f6044f5727ad9a8c9752574cacdce03d?s=96&d=mm&r=g","caption":"INTARCON"}}]}},"_links":{"self":[{"href":"https:\/\/www.intarcon.com\/de\/wp-json\/wp\/v2\/posts\/77061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intarcon.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.intarcon.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.intarcon.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.intarcon.com\/de\/wp-json\/wp\/v2\/comments?post=77061"}],"version-history":[{"count":0,"href":"https:\/\/www.intarcon.com\/de\/wp-json\/wp\/v2\/posts\/77061\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intarcon.com\/de\/wp-json\/wp\/v2\/media\/58154"}],"wp:attachment":[{"href":"https:\/\/www.intarcon.com\/de\/wp-json\/wp\/v2\/media?parent=77061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.intarcon.com\/de\/wp-json\/wp\/v2\/categories?post=77061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.intarcon.com\/de\/wp-json\/wp\/v2\/tags?post=77061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}